{"id":2376,"date":"2021-08-04T18:20:18","date_gmt":"2021-08-04T21:20:18","guid":{"rendered":"https:\/\/pluscargo.com.br\/?p=2376"},"modified":"2021-08-04T18:20:18","modified_gmt":"2021-08-04T21:20:18","slug":"a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental","status":"publish","type":"post","link":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/","title":{"rendered":"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental"},"content":{"rendered":"\n<p>O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.<\/p>\n\n\n\n<p>Aqui na Pluscargo Brasil, antes mesmo do isolamento social causado pela pandemia de Covid-19, cuidar da sa\u00fade sempre foi um tema de muita relev\u00e2ncia. Alguns dos colaboradores participam do grupo de triatlo, modalidade esportiva que une nata\u00e7\u00e3o, corrida e ciclismo e, agora no home office, essa pauta ganhou ainda mais for\u00e7a. Nossos encontros semanais contam com diversos assuntos, inclusive sobre sa\u00fade.<\/p>\n\n\n\n<p>Al\u00e9m da dedica\u00e7\u00e3o e disciplina, que podem ajudar n\u00e3o s\u00f3 nos exerc\u00edcios, a disposi\u00e7\u00e3o e equil\u00edbrio f\u00edsico e mental tamb\u00e9m s\u00e3o resultados positivos que o esporte pode trazer. Marcelo Antonio, do escrit\u00f3rio de Santos, pratica exerc\u00edcios h\u00e1 mais de 15 anos e o esporte j\u00e1 faz parte de sua rotina.<\/p>\n\n\n\n<p>\u201cO meu auge no esporte foi quando fui selecionado para participar do triatlo com a Plus. Pude conhecer diversas pessoas que praticavam o esporte e pude perceber o quanto \u00e9 apaixonante\u201d.<\/p>\n\n\n\n<p>Para Marcelo, praticar exerc\u00edcios tamb\u00e9m contribui com a mudan\u00e7a de rotina e diminui o n\u00edvel de estresse, especialmente no per\u00edodo de quarentena. \u201cQuando a quarentena estava severa, era muito estressante ficar preso em casa e praticar esporte ajudava a n\u00e3o ficar louco, rs\u201d comenta.<\/p>\n\n\n\n<p>Luciano Ferreira, que faz parte da mesma unidade, tamb\u00e9m tem uma boa rela\u00e7\u00e3o com exerc\u00edcios. Com o incentivo da Pluscargo Brasil, iniciou no triatlo e desde ent\u00e3o se encontrou nesta modalidade e n\u00e3o abre m\u00e3o de praticar.<\/p>\n\n\n\n<p>Al\u00e9m de ajudar na rotina, com o aumento da disposi\u00e7\u00e3o e foco, a pr\u00e1tica esportiva tamb\u00e9m ajudou Luciano a superar um recente luto. \u201cEu acredito que, sim, o esporte ajuda na rotina, pois ele deixa a gente mais ligado e disposto a realizar qualquer tipo de trabalho, deixando a gente mais focado tamb\u00e9m. \u00c9 a melhor maneira de viver a vida e trabalhar.\u201d<\/p>\n\n\n\n<p>&nbsp;O #esportenaPLUS, sempre foi e ainda continua sendo um importante aliado. Acreditamos que o bem-estar e a sa\u00fade devem ser prioridade na rotina de todos os colaboradores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel. Aqui na Pluscargo Brasil, antes mesmo do isolamento social causado pela pandemia de Covid-19, cuidar da sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[48,173,174,27],"class_list":["post-2376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","tag-comercio-exterior","tag-dia-nacional-da-saude","tag-esporte-na-plus","tag-pluscargo-brasil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo<\/title>\n<meta name=\"description\" content=\"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo\" \/>\n<meta property=\"og:description\" content=\"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Pluscargo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pluscargobrasil\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T21:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patricia Bar\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Bar\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/\"},\"author\":{\"name\":\"Patricia Bar\u00e3o\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/#\\\/schema\\\/person\\\/823aef0643611f95b501442c8e899668\"},\"headline\":\"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental\",\"datePublished\":\"2021-08-04T21:20:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/210805_DiaDaSaude_Site_V4.png\",\"keywords\":[\"com\u00e9rcio exterior\",\"Dia Nacional da Sa\u00fade\",\"Esporte na Plus\",\"Pluscargo Brasil\"],\"articleSection\":[\"Acontece na PLUS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/\",\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/\",\"name\":\"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/210805_DiaDaSaude_Site_V4.png\",\"datePublished\":\"2021-08-04T21:20:18+00:00\",\"description\":\"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/210805_DiaDaSaude_Site_V4.png\",\"contentUrl\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/210805_DiaDaSaude_Site_V4.png\",\"width\":720,\"height\":482,\"caption\":\"Esporte na Plus e Dia Nacional da Sa\u00fade\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/\",\"name\":\"Pluscargo\",\"description\":\"A Pluscargo \u00e9 uma empresa do Grupo RAS, o maior ecossistema log\u00edstico da Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#organization\",\"name\":\"Pluscargo Brasil\",\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Pluscargo_Logo.png\",\"contentUrl\":\"https:\\\/\\\/pluscargo.com.br\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Pluscargo_Logo.png\",\"width\":3063,\"height\":518,\"caption\":\"Pluscargo Brasil\"},\"image\":{\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pluscargobrasil\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pluscargo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pluscargo-do-brasil-ltda\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pluscargo.com.br\\\/#\\\/schema\\\/person\\\/823aef0643611f95b501442c8e899668\",\"name\":\"Patricia Bar\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g\",\"caption\":\"Patricia Bar\u00e3o\"},\"url\":\"https:\\\/\\\/pluscargo.com.br\\\/en\\\/author\\\/patriciabarao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo","description":"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/","og_locale":"en_US","og_type":"article","og_title":"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo","og_description":"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.","og_url":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/","og_site_name":"Pluscargo","article_publisher":"https:\/\/www.facebook.com\/pluscargobrasil\/","article_published_time":"2021-08-04T21:20:18+00:00","og_image":[{"width":720,"height":482,"url":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png","type":"image\/png"}],"author":"Patricia Bar\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Patricia Bar\u00e3o","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pluscargo.com.br\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/#article","isPartOf":{"@id":"https:\/\/pluscargo.com.br\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/"},"author":{"name":"Patricia Bar\u00e3o","@id":"https:\/\/pluscargo.com.br\/#\/schema\/person\/823aef0643611f95b501442c8e899668"},"headline":"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental","datePublished":"2021-08-04T21:20:18+00:00","mainEntityOfPage":{"@id":"https:\/\/pluscargo.com.br\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/pluscargo.com.br\/#organization"},"image":{"@id":"https:\/\/pluscargo.com.br\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png","keywords":["com\u00e9rcio exterior","Dia Nacional da Sa\u00fade","Esporte na Plus","Pluscargo Brasil"],"articleSection":["Acontece na PLUS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/","url":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/","name":"A import\u00e2ncia da pr\u00e1tica de esportes para a sa\u00fade f\u00edsica e mental - Pluscargo","isPartOf":{"@id":"https:\/\/pluscargo.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/#primaryimage"},"image":{"@id":"https:\/\/pluscargo.com.br\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png","datePublished":"2021-08-04T21:20:18+00:00","description":"O Dia Nacional da Sa\u00fade tem como uma de suas finalidades lembrar a import\u00e2ncia de manter bons h\u00e1bitos com a sa\u00fade f\u00edsica e mental, pois ambas caminham juntas e s\u00e3o essenciais para o bem-estar e uma vida saud\u00e1vel.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pluscargo.com.br\/en\/a-importancia-da-pratica-de-esportes-para-a-saude-fisica-e-mental\/#primaryimage","url":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png","contentUrl":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2021\/08\/210805_DiaDaSaude_Site_V4.png","width":720,"height":482,"caption":"Esporte na Plus e Dia Nacional da Sa\u00fade"},{"@type":"WebSite","@id":"https:\/\/pluscargo.com.br\/en\/#website","url":"https:\/\/pluscargo.com.br\/en\/","name":"Pluscargo","description":"A Pluscargo \u00e9 uma empresa do Grupo RAS, o maior ecossistema log\u00edstico da Am\u00e9rica Latina","publisher":{"@id":"https:\/\/pluscargo.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pluscargo.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pluscargo.com.br\/en\/#organization","name":"Pluscargo Brasil","url":"https:\/\/pluscargo.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pluscargo.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2019\/02\/Pluscargo_Logo.png","contentUrl":"https:\/\/pluscargo.com.br\/wp-content\/uploads\/2019\/02\/Pluscargo_Logo.png","width":3063,"height":518,"caption":"Pluscargo Brasil"},"image":{"@id":"https:\/\/pluscargo.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pluscargobrasil\/","https:\/\/www.instagram.com\/pluscargo\/","https:\/\/www.linkedin.com\/company\/pluscargo-do-brasil-ltda"]},{"@type":"Person","@id":"https:\/\/pluscargo.com.br\/#\/schema\/person\/823aef0643611f95b501442c8e899668","name":"Patricia Bar\u00e3o","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3494dbde84fcb1f8f0da772094ccf26c5ce8eaf1d167b8835ffc8f82efe4b83b?s=96&d=mm&r=g","caption":"Patricia Bar\u00e3o"},"url":"https:\/\/pluscargo.com.br\/en\/author\/patriciabarao\/"}]}},"_links":{"self":[{"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/posts\/2376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/comments?post=2376"}],"version-history":[{"count":0,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/posts\/2376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/media\/2377"}],"wp:attachment":[{"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/media?parent=2376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/categories?post=2376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pluscargo.com.br\/en\/wp-json\/wp\/v2\/tags?post=2376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}